{"id":1682,"date":"2025-06-02T11:52:09","date_gmt":"2025-06-02T10:52:09","guid":{"rendered":"https:\/\/la-cortigiana.it\/?p=1682"},"modified":"2025-07-25T11:40:17","modified_gmt":"2025-07-25T10:40:17","slug":"palazzo-dandolo-where-masks-fell-behind-locked-doors","status":"publish","type":"post","link":"https:\/\/la-cortigiana.it\/de\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/","title":{"rendered":"Palazzo Dandolo: Wo Masken hinter verschlossenen T\u00fcren fielen"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wenn das Ridotto Venedigs offizielle B\u00fchne der Versuchung war, dann <strong>Palazzo Dandolo<\/strong> war sein privater Backstage-Bereich \u2013 der Ort, an dem das Vergn\u00fcgen kein Publikum mehr brauchte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das heutige Hotel Danieli steht stolz an der Riva degli Schiavoni und verbirgt, was es einst war: eines der dekadentesten, gef\u00e4hrlichsten und sorgf\u00e4ltig orchestrierten Erotiktheater des goldenen Zeitalters Venedigs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend der Karnevalszeit, als Venedig sich hinter Masken der Anonymit\u00e4t hingab, wurden die gro\u00dfen Salons des Palazzo Dandolo zu etwas weitaus Intimerem als \u00f6ffentliche Spielhallen. Hier, fernab vom Stra\u00dfenl\u00e4rm, legten die Adligen nicht nur ihre Verkleidungen, sondern auch ihre Selbstbeherrschung ab. Hinter schweren Samtvorh\u00e4ngen, bei flackerndem Kerzenlicht und mit mythologischen G\u00f6ttern bemalten Decken wurden B\u00fcndnisse geschlossen, Schulden mit Fleisch beglichen und Skandale im Stillen geboren.<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1530\" height=\"1530\" src=\"https:\/\/i0.wp.com\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933.jpg?fit=1200%2C1200&amp;ssl=1\" alt=\"\" class=\"wp-image-1684 size-full\" srcset=\"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933.jpg 1530w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-300x300.jpg 300w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-100x100.jpg 100w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-600x600.jpg 600w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-500x500.jpg 500w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-1200x1200.jpg 1200w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-768x768.jpg 768w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-12x12.jpg 12w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-150x150.jpg 150w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-75x75.jpg 75w, https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/3_Lobby_1400x933-480x480.jpg 480w\" sizes=\"(max-width: 1530px) 100vw, 1530px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">Die Familie Dandolo \u2013 eines der \u00e4ltesten Adelsh\u00e4user Venedigs \u2013 beherrschte schon lange die Kunst, politischen Einfluss und private Gen\u00fcsse zu vereinen. Im 17. und 18. Jahrhundert wurde der Palazzo w\u00e4hrend des Karnevals regelm\u00e4\u00dfig f\u00fcr exklusive Privatb\u00e4lle vermietet. Anders als beim \u00f6ffentlichen Spektakel des Ridotto waren die Einladungen hier selektiv.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prinzen, Botschafter, Kardin\u00e4le und reiche Kaufleute trafen in stillen Gondeln an den Seiteneing\u00e4ngen ein, begleitet von maskierten Frauen, deren wahre Identit\u00e4t nur wenigen bekannt war \u2013 oft denjenigen, die ihre Diskretion im Voraus erkauft hatten.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In diesen vergoldeten Hallen wurde nicht einfach nur Sex gehandelt. Es war <strong>Zugang<\/strong>Kurtisanen, die in den Dandolo-R\u00e4umen arbeiteten, fungierten oft als inoffizielle Vermittler zwischen rivalisierenden Fraktionen und gaben Geheimnisse preis, die zwischen den Laken gefl\u00fcstert wurden. Ausl\u00e4ndische Gesandte lie\u00dfen sich private Treffen mit Frauen, die \u2013 manchmal unwissentlich \u2013 direkt dem Rat der Zehn Bericht erstatten konnten, teuer bezahlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein gefl\u00fcsterter Skandal betraf eine Aff\u00e4re zwischen <strong>Kardinal Ludovico Sagredo<\/strong> und die Geliebte des franz\u00f6sischen Botschafters \u2013 eine Kurtisane, die nur als \u201eLa Bianca\u201c bekannt war \u2013, von der es hei\u00dft, sie habe nach ihren n\u00e4chtlichen Begegnungen in Dandolos roten Gem\u00e4chern Staatsgeheimnisse direkt an die pers\u00f6nlichen Spione des Dogen weitergegeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und nat\u00fcrlich <strong>Giacomo Casanova<\/strong> war im Palazzo Dandolo kein Unbekannter. In seinen Memoiren schreibt er, wie er zu geheimen Maskenabendessen hierher geschmuggelt wurde, bei denen Adlige gef\u00e4hrliche Machtspiele spielten und sich manchmal gegenseitig herausforderten, ihre Masken ganz abzunehmen \u2013 eine Geste, die weitaus intimer war als Nacktheit selbst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend die Stadt oben ihr Bild streng katholischen Anstands bewahrte, war die Realit\u00e4t in Dandolo weitaus komplexer. Ganze Ehevertr\u00e4ge wurden hier aufgel\u00f6st. Erpresserbriefe wurden verfasst. Mitgiften ausgehandelt. Sogar politische Karrieren wurden gestartet oder zerst\u00f6rt \u2013 oft basierend auf dem, was in der Privatsph\u00e4re dieser verbotenen R\u00e4ume vereinbart wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Napoleon 1797 eintraf, brach der Karneval \u2013 und Venedig selbst \u2013 unter der Fremdherrschaft zusammen. Die Maskenspiele im Palazzo Dandolo waren Geschichte. Doch der Palazzo \u00fcberlebte und verwandelte sich in das Luxushotel Danieli, das noch immer Zimmer mit Aussicht bot \u2013 allerdings inzwischen deutlich hygienischer als jene, die seine G\u00e4ste einst f\u00fcr weitaus d\u00fcsterere Zwecke mieteten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Touristen bewundern heute die Marmors\u00e4ulen und die geschwungene Treppe, ohne zu wissen, dass in denselben Hallen einst das Gefl\u00fcster von Namen, geheimen B\u00fcndnissen und unter Seidenlaken aneinandergepressten K\u00f6rpern widerhallte, w\u00e4hrend drau\u00dfen Gondoliere Wache standen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denn in Venedig war Verf\u00fchrung nie eine Nebensache.<br>Es war das ganze Spiel.<\/p>","protected":false},"excerpt":{"rendered":"<p>If the Ridotto was Venice\u2019s official stage for temptation, then Palazzo Dandolo was its private backstage \u2014 the place where [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","googlesitekit_rrm_CAowrc_CDA:productID":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ai_generated_summary":"","footnotes":""},"categories":[238],"tags":[],"class_list":["post-1682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-history"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Palazzo Dandolo: Where Masks Fell Behind Locked Doors -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/la-cortigiana.it\/de\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palazzo Dandolo: Where Masks Fell Behind Locked Doors\" \/>\n<meta property=\"og:description\" content=\"If the Ridotto was Venice\u2019s official stage for temptation, then Palazzo Dandolo was its private backstage \u2014 the place where [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/la-cortigiana.it\/de\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LaCortigiana\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-02T10:52:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-25T10:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/DSCF9392.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"LaCortigiana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@la_cortigianait\" \/>\n<meta name=\"twitter:site\" content=\"@la_cortigianait\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"LaCortigiana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/\"},\"author\":{\"name\":\"LaCortigiana\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#\\\/schema\\\/person\\\/13a756297820a075c4ba4c21b4c4c70a\"},\"headline\":\"Palazzo Dandolo: Where Masks Fell Behind Locked Doors\",\"datePublished\":\"2025-06-02T10:52:09+00:00\",\"dateModified\":\"2025-07-25T10:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/\"},\"wordCount\":522,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/la-cortigiana.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/DSCF9392.webp\",\"articleSection\":[\"Art &amp; History\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/\",\"url\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/\",\"name\":\"Palazzo Dandolo: Where Masks Fell Behind Locked Doors -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/la-cortigiana.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/DSCF9392.webp\",\"datePublished\":\"2025-06-02T10:52:09+00:00\",\"dateModified\":\"2025-07-25T10:40:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/la-cortigiana.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/DSCF9392.webp\",\"contentUrl\":\"https:\\\/\\\/la-cortigiana.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/DSCF9392.webp\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/palazzo-dandolo-where-masks-fell-behind-locked-doors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/la-cortigiana.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palazzo Dandolo: Where Masks Fell Behind Locked Doors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#website\",\"url\":\"https:\\\/\\\/la-cortigiana.it\\\/\",\"name\":\"La Cortigiana | Discreet Symbol Jewelry & Erotic Leather, Handmade in Italy\",\"description\":\"Quiet Marks of Chosen Desire\",\"publisher\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/la-cortigiana.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#organization\",\"name\":\"La Cortigiana\",\"url\":\"https:\\\/\\\/la-cortigiana.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/la-cortigiana.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/La-Cortigiana.png\",\"contentUrl\":\"https:\\\/\\\/la-cortigiana.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/La-Cortigiana.png\",\"width\":1646,\"height\":575,\"caption\":\"La Cortigiana\"},\"image\":{\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaCortigiana\\\/\",\"https:\\\/\\\/x.com\\\/la_cortigianait\",\"https:\\\/\\\/www.instagram.com\\\/la_cortigiana.it\",\"https:\\\/\\\/substack.com\\\/@lacortigiana\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/la-cortigiana.it\\\/#\\\/schema\\\/person\\\/13a756297820a075c4ba4c21b4c4c70a\",\"name\":\"LaCortigiana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca1f04e1935d1ac6e07856bf21ca89093b47bf4ff9fcc4602662eac8e2c42884?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca1f04e1935d1ac6e07856bf21ca89093b47bf4ff9fcc4602662eac8e2c42884?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca1f04e1935d1ac6e07856bf21ca89093b47bf4ff9fcc4602662eac8e2c42884?s=96&d=mm&r=g\",\"caption\":\"LaCortigiana\"},\"url\":\"https:\\\/\\\/la-cortigiana.it\\\/de\\\/author\\\/lacortigiana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palazzo Dandolo: Where Masks Fell Behind Locked Doors -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/la-cortigiana.it\/de\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/","og_locale":"de_DE","og_type":"article","og_title":"Palazzo Dandolo: Where Masks Fell Behind Locked Doors","og_description":"If the Ridotto was Venice\u2019s official stage for temptation, then Palazzo Dandolo was its private backstage \u2014 the place where [&hellip;]","og_url":"https:\/\/la-cortigiana.it\/de\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/","article_publisher":"https:\/\/www.facebook.com\/LaCortigiana\/","article_published_time":"2025-06-02T10:52:09+00:00","article_modified_time":"2025-07-25T10:40:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/DSCF9392.webp","type":"image\/webp"}],"author":"LaCortigiana","twitter_card":"summary_large_image","twitter_creator":"@la_cortigianait","twitter_site":"@la_cortigianait","twitter_misc":{"Verfasst von":"LaCortigiana","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#article","isPartOf":{"@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/"},"author":{"name":"LaCortigiana","@id":"https:\/\/la-cortigiana.it\/#\/schema\/person\/13a756297820a075c4ba4c21b4c4c70a"},"headline":"Palazzo Dandolo: Where Masks Fell Behind Locked Doors","datePublished":"2025-06-02T10:52:09+00:00","dateModified":"2025-07-25T10:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/"},"wordCount":522,"commentCount":0,"publisher":{"@id":"https:\/\/la-cortigiana.it\/#organization"},"image":{"@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#primaryimage"},"thumbnailUrl":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/DSCF9392.webp","articleSection":["Art &amp; History"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/","url":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/","name":"Palazzo Dandolo: Where Masks Fell Behind Locked Doors -","isPartOf":{"@id":"https:\/\/la-cortigiana.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#primaryimage"},"image":{"@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#primaryimage"},"thumbnailUrl":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/DSCF9392.webp","datePublished":"2025-06-02T10:52:09+00:00","dateModified":"2025-07-25T10:40:17+00:00","breadcrumb":{"@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#primaryimage","url":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/DSCF9392.webp","contentUrl":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/06\/DSCF9392.webp","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/la-cortigiana.it\/palazzo-dandolo-where-masks-fell-behind-locked-doors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/la-cortigiana.it\/"},{"@type":"ListItem","position":2,"name":"Palazzo Dandolo: Where Masks Fell Behind Locked Doors"}]},{"@type":"WebSite","@id":"https:\/\/la-cortigiana.it\/#website","url":"https:\/\/la-cortigiana.it\/","name":"La Cortigiana | Diskret-symbolischer Schmuck &amp; erotisches Leder, handgefertigt in Italien","description":"Stille Zeichen erw\u00e4hlten Verlangens","publisher":{"@id":"https:\/\/la-cortigiana.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/la-cortigiana.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/la-cortigiana.it\/#organization","name":"La Cortigiana","url":"https:\/\/la-cortigiana.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/la-cortigiana.it\/#\/schema\/logo\/image\/","url":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/01\/La-Cortigiana.png","contentUrl":"https:\/\/la-cortigiana.it\/wp-content\/uploads\/2025\/01\/La-Cortigiana.png","width":1646,"height":575,"caption":"La Cortigiana"},"image":{"@id":"https:\/\/la-cortigiana.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaCortigiana\/","https:\/\/x.com\/la_cortigianait","https:\/\/www.instagram.com\/la_cortigiana.it","https:\/\/substack.com\/@lacortigiana"]},{"@type":"Person","@id":"https:\/\/la-cortigiana.it\/#\/schema\/person\/13a756297820a075c4ba4c21b4c4c70a","name":"LaCortigiana","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ca1f04e1935d1ac6e07856bf21ca89093b47bf4ff9fcc4602662eac8e2c42884?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca1f04e1935d1ac6e07856bf21ca89093b47bf4ff9fcc4602662eac8e2c42884?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca1f04e1935d1ac6e07856bf21ca89093b47bf4ff9fcc4602662eac8e2c42884?s=96&d=mm&r=g","caption":"LaCortigiana"},"url":"https:\/\/la-cortigiana.it\/de\/author\/lacortigiana\/"}]}},"_links":{"self":[{"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/posts\/1682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/comments?post=1682"}],"version-history":[{"count":1,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/posts\/1682\/revisions"}],"predecessor-version":[{"id":1685,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/posts\/1682\/revisions\/1685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/media\/1683"}],"wp:attachment":[{"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/media?parent=1682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/categories?post=1682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/la-cortigiana.it\/de\/wp-json\/wp\/v2\/tags?post=1682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}